{"id":72648,"date":"2025-04-01T06:39:05","date_gmt":"2025-04-01T06:39:05","guid":{"rendered":"https:\/\/gostudyin.com\/vietnam\/institutes\/kings-college\/"},"modified":"2026-08-18T13:45:09","modified_gmt":"2026-08-18T06:45:09","slug":"kings-college","status":"publish","type":"institution","link":"https:\/\/gostudyin.com\/vietnam\/study-in-uk\/institutes\/universities\/kings-college\/","title":{"rendered":"King&#8217;s College London"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-72648","institution","type-institution","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/gostudyin.com\/vietnam\/wp-json\/wp\/v2\/institution\/72648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gostudyin.com\/vietnam\/wp-json\/wp\/v2\/institution"}],"about":[{"href":"https:\/\/gostudyin.com\/vietnam\/wp-json\/wp\/v2\/types\/institution"}],"wp:attachment":[{"href":"https:\/\/gostudyin.com\/vietnam\/wp-json\/wp\/v2\/media?parent=72648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}